{"id":4491,"date":"2021-02-04T15:34:29","date_gmt":"2021-02-04T14:34:29","guid":{"rendered":"https:\/\/www.topblogs.de\/magazin\/?p=4491"},"modified":"2021-02-04T15:34:33","modified_gmt":"2021-02-04T14:34:33","slug":"versicherung-was-ist-denn-der-unterschied","status":"publish","type":"post","link":"https:\/\/www.topblogs.de\/magazin\/versicherung-was-ist-denn-der-unterschied\/","title":{"rendered":"Versicherung: Was ist denn der Unterschied?"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Warum ein Makler f\u00fcr bestimmte Gruppen interessant ist<\/h3>\n\n\n\n<p>Versicherungen braucht jeder. Nur was ist denn der Unterschied, ob ich mich an einen Makler, einen Vertreter oder einen Versicherungsberater wende? Es gibt grundlegende Unterschiede, welche erhebliche Auswirkungen haben. Sicher ist es auch eine Frage, ob sich eine Privatperson versichert oder hierf\u00fcr berufliche Hintergr\u00fcnde eine Rolle spielen.<br>Von Uwe Finkelmeyer-Urban<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Unabh\u00e4ngig, aber nicht kostenlos: Der Versicherungsberater<\/h3>\n\n\n\n<p><br>Unabh\u00e4ngige Beratung ist am ehesten dann zu erwarten, wenn keine wirtschaftliche Verflechtung zwischen dem Berater und der zu beratenden Leistung besteht. Ein Vertreter, der provisionsm\u00e4\u00dfig bezahlt wird, steht selbstverst\u00e4ndlich im Verdacht, nicht neutral zu beraten. Schlie\u00dflich lebt er von der Provision und dem Verkauf. Hier setzt der Versicherungsberater an. Er ber\u00e4t, verkauft aber nicht. F\u00fcr seine Dienstleistung erh\u00e4lt er das vereinbarte Beraterhonorar. Dieses liegt zwischen 100\u2013150 Euro die Stunde. Klingt zun\u00e4chst nach viel Geld, aber vor dem Hintergrund, dass eine Falschberatung \u2013 insbesondere bei der finanziellen Alterssicherung \u2013 erhebliche Einbu\u00dfen bis hin zu Verlusten bringen kann, erscheint der Stundensatz moderat. Da in den Versicherungspr\u00e4mien regelm\u00e4\u00dfig die Abschlusskosten, also die Provision des Vertreters oder Maklers, eingerechnet ist, gibt es entsprechende Honorartarife. Diesen Tarifen wurden alle Vertriebskosten herausgerechnet. Das kann sich bei langen Laufzeiten erheblich auswirken, da gerade bei Investmentfonds sogenannte Kick-Backs dem Kunden gutgeschrieben werden und positiv zur Gesamtrendite beitragen. Dem Versicherungsberater<br>ist es auch untersagt, Geld von Versicherungen anzunehmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Am Markt gibt es eine Reihe namhafter Unternehmen, die entsprechende Honorartarife anbieten.<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><a href=\"https:\/\/www.topblogs.de\/magazin\/wp-content\/uploads\/2021\/02\/BeratungFrau.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.topblogs.de\/magazin\/wp-content\/uploads\/2021\/02\/BeratungFrau.jpg\" alt=\"\" class=\"wp-image-4497\"\/><\/a><\/figure><\/div>\n\n\n\n<p><br>Grundlage der Verg\u00fctung ist der geschlossene Beratervertrag. Aus diesem Vertrag ergibt sich auch eine Haftung des Beraters dem Kunden gegen\u00fcber. Welche Haftung ein Berater dem Kunden im konkreten Fall schuldet, kommt auf den vertraglichen Inhalt an. Ist der Beratungsgegenstand weit gefasst, also soll der Berater die gesamte finanzielle Situation des Kunden erfassen, oder handelt es sich um einen Teilbereich des Kundeninteresses, beispielsweise der Kunde m\u00f6chte seinen Fuhrpark mit Oldtimern entsprechend versichert<br>haben. Relevant ist au\u00dferdem, ob als vertragliche Leistung lediglich die Beratung vereinbart wird oder ob auch \u201edas in die Wege leiten&#8220; Vertragsgegenstand ist. Im letzteren Fall w\u00e4re die ordnungsgem\u00e4\u00dfe Beantragung entsprechender Policen ebenso geschuldet. Die<br>unterschiedlichen Rechtsfolgen k\u00f6nnen gravierend sein. Ist es ein Dienstvertrag (erster Fall) nach \u00a7 611 BGB oder ein Werkvertrag entsprechend \u00a7 631 BGB (zweiter Fall), bei dem neben der Beratung auch eine Leistung als Erfolg (die ordnungsgem\u00e4\u00dfe Antragstellung) geschuldet wird. Je nachdem, was vereinbart ist, geh\u00f6rt zur Pflicht des Beraters, die Policierung zu \u00fcberwachen. Ein denkbarer Fall w\u00e4re beispielsweise die Ablehnung einer Lebensversicherung durch das Versicherungsunternehmen aufgrund gesundheitlicher Merkmale der zu versichernden Person. Hier m\u00fcsste der Berater bei Nichtpolicierung aktiv werden und nach weiteren Optionen Ausschau halten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Versicherungsmakler im Auftrag des Kunden<\/h3>\n\n\n\n<p><br>Grundlage f\u00fcr die Maklert\u00e4tigkeit ist der Maklervertrag. Er ist ein<br>Gesch\u00e4ftsbesorgungsauftrag, der Makler tritt im Auftrag des Kunden auf. Er vertritt das Kundeninteresse, nicht das der Versicherung. Auch hier ist wesentlich, was vertraglich vereinbart wurde, also welche Kundeninteressen hat der Makler zu vertreten. Nehmen wir an, der Kunde sei selbstst\u00e4ndig, ist lediglich die berufliche T\u00e4tigkeit Vertragsgegenstand oder ist es seine komplette finanzielle Absicherung. Bei Haftungsfragen hat das erhebliche<br>Auswirkungen.<\/p>\n\n\n\n<p><br>Selbstst\u00e4ndige, Firmeninhaber und Freiberufler tragen regelm\u00e4\u00dfig gr\u00f6\u00dfere Risiken. Ein Arzt (freier Beruf) sieht sich medizinischen Haftungsfragen ausgesetzt. Also muss er eine entsprechende Berufshaftpflichtversicherung abschlie\u00dfen. Genauso ist es beim Steuerberater, er sieht sich eher verm\u00f6gensrechtlichen Schadensersatzanspr\u00fcchen ausgesetzt. Oder ein Gewerbebetrieb, hier m\u00fcssen alle versicherungsrelevanten Punkte<br>beachtet werden. Der Makler muss die Kundensituation analysieren und entsprechend eindecken, damit der Kunde im Schadensfall abgesichert ist. Beispielhaft w\u00e4re die Betriebsausfallversicherung einer Schreinerei, welche aufgrund eines Brandes l\u00e4ngere Zeit einen Produktionsausfall erleidet. All diese mit dem Gewerbebetrieb einhergehenden Risiken (bei der Schreinerei sind es auch Haftungsfragen, also Betriebshaftpflicht) muss der Makler (und der Versicherungsberater) erkennen. Entsprechend hat er dann die Risiken<br>einzudecken. Hier muss der Makler im Kundeninteresse mehrere Anbieter vergleichen, um das beste Angebot f\u00fcr seinen Mandanten zu finden. Er hat diesen Prozess zu dokumentieren \u2013 und \u2013 ganz wichtig, sich auch vom Kunden unterschreiben zu lassen, wenn dieser ein erkanntes Risiko nicht versichert wissen will. Merksatz w\u00e4re folgender: Beim Makler unterschreibt der Kunde, wenn er keine Versicherung will, beim Vertreter, wenn er eine m\u00f6chte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br>Herr Kaiser gr\u00fc\u00dft die Welt<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><a href=\"https:\/\/www.topblogs.de\/magazin\/wp-content\/uploads\/2021\/02\/Beratung.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.topblogs.de\/magazin\/wp-content\/uploads\/2021\/02\/Beratung.jpg\" alt=\"\" class=\"wp-image-4495\"\/><\/a><\/figure><\/div>\n\n\n\n<p><br>Der Versicherungsvertreter tritt im Auftrag des Unternehmens auf. Er vertritt die Versicherung nach au\u00dfen. Sein Angebot ist auf das Portfolio des Arbeitgebers begrenzt. Haftungsfragen richten sich an das Unternehmen. Die Aussagen und Handlungen des Vertreters muss es sich zurechnen lassen. Die Grenze der Zurechnung ist bei grober Fahrl\u00e4ssigkeit oder Vorsatz zu sehen.<\/p>\n\n\n\n<p><br>Des Kaisers Beratung ist kostenlos. Zun\u00e4chst. Schlie\u00dflich erh\u00e4lt er f\u00fcr abgeschlossene Vertr\u00e4ge Provision. Je nachdem, welche Jahreszeit ist, gibt es Gesch\u00e4ftspl\u00e4ne der Versicherung, die der Vertrieb erreichen soll. Diese Gesch\u00e4ftsziele werden extra honoriert. Beispielsweise mit einer Superprovision oder einer Reise (bestenfalls beides), bei der neben<br>Alkohol auch schon leicht bekleidete Damen gereicht wurden. Ergo muss man die Objektivit\u00e4t der Vertreter hinterfragen. Sicherlich gibt es in einer Herde schwarzer Schafe auch wei\u00dfe \u2013 und umgekehrt. Ein vertragliches Verh\u00e4ltnis besteht zwischen dem Versicherungsagenten und dem Kunden nicht. Das Vertragsverh\u00e4ltnis ist auf die abgeschlossenen Vertr\u00e4ge begrenzt. Nicht<br>versicherte Risiken unterliegen weder der Haftung der Versicherung noch ihres Vertreters. Schlie\u00dflich ist die Leistung auf die Produkte des Unternehmens begrenzt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Der Einzelfall entscheidet.<\/h3>\n\n\n\n<p>Es ist die Gr\u00f6\u00dfe des Beratungsbedarfs entscheidend, ob ich einen Versicherungsagenten-, Makler oder Berater kontaktiere. M\u00f6chte ich lediglich ein Versicherungskennzeichen meines Mopeds oder m\u00fcssen berufliche, betriebliche oder private Risiken abgesichert werden. Oder eben eine Mischung aus beiden Bereichen. Je komplexer der Beratungs- und<br>Versicherungsbedarf ist, umso eher ist angeraten, sich an einen Makler oder Berater zu wenden. Der Makler wird im Gegensatz zum Berater von der Versicherung durch Provision bezahlt. Daf\u00fcr ist seine Beratung kostenlos. Der Berater kostet Geld, aber guter Rat ist teuer. Das sagt bereits das Sprichwort. Beide haften dem Kunden gegen\u00fcber allerdings umfassend. Es ist also dann eine pers\u00f6nliche Entscheidung, an wen man sich wendet. Oder auch eine, ob<br>ein Versicherungsberater in der N\u00e4he ist. Diese gibt es im Gegensatz zu den Armeen an Vertretern nur sp\u00e4rlich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Warum ein Makler f\u00fcr bestimmte Gruppen interessant ist Versicherungen braucht jeder. Nur was ist denn der Unterschied, ob ich mich<\/p>\n","protected":false},"author":1,"featured_media":4493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[4],"tags":[19],"class_list":["post-4491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","tag-recht-gesetz"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/posts\/4491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/comments?post=4491"}],"version-history":[{"count":3,"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/posts\/4491\/revisions"}],"predecessor-version":[{"id":4498,"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/posts\/4491\/revisions\/4498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/media\/4493"}],"wp:attachment":[{"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/media?parent=4491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/categories?post=4491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.topblogs.de\/magazin\/wp-json\/wp\/v2\/tags?post=4491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}